{"id":5530,"date":"2024-07-09T19:00:34","date_gmt":"2024-07-09T19:00:34","guid":{"rendered":"https:\/\/did-dev.net\/mineddte\/?p=5530"},"modified":"2024-07-25T09:29:44","modified_gmt":"2024-07-25T09:29:44","slug":"zone-portuaire-dabidjan-persistance-des-poussieres-de-ciment-le-ministre-assahore-invite-les-acteurs-au-respect-des-normes-environnementales","status":"publish","type":"post","link":"https:\/\/did-dev.net\/mineddte\/zone-portuaire-dabidjan-persistance-des-poussieres-de-ciment-le-ministre-assahore-invite-les-acteurs-au-respect-des-normes-environnementales\/","title":{"rendered":"ZONE PORTUAIRE D\u2019ABIDJAN \/ PERSISTANCE DES POUSSI\u00c8RES DE CIMENT : LE MINISTRE ASSAHOR\u00c9 INVITE LES ACTEURS AU RESPECT DES NORMES ENVIRONNEMENTALES"},"content":{"rendered":"<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\">\n<div dir=\"auto\" style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-5531\" src=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/07\/Sans-titre-1-01-1-scaled.jpg\" alt=\"\" width=\"2560\" height=\"948\" srcset=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/07\/Sans-titre-1-01-1-scaled.jpg 2560w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/07\/Sans-titre-1-01-1-262x97.jpg 262w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/07\/Sans-titre-1-01-1-847x314.jpg 847w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/07\/Sans-titre-1-01-1-100x37.jpg 100w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/07\/Sans-titre-1-01-1-1536x569.jpg 1536w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/07\/Sans-titre-1-01-1-2048x758.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div>\n<div dir=\"auto\" style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">\u00ab On ne peut plus continuer \u00e0 mettre en balance la vie de la population avec des imp\u00e9ratifs \u00e9conomiques. Qu&#8217;est-ce que \u00e7a vaut d&#8217;avoir le prix du ciment bas si cela met en danger la vie des populations ? \u00bb a interrog\u00e9 avec insistance M. Assahor\u00e9 Konan Jacques, Ministre de l&#8217;Environnement, du D\u00e9veloppement Durable et de la Transition \u00c9cologique, lors de la rencontre avec les acteurs du secteur de la cimenterie, le mardi 9 juillet 2024, \u00e0 son cabinet.<\/span><\/div>\n<div dir=\"auto\" style=\"text-align: justify;\">\u00a0<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: justify;\">\n<div dir=\"auto\"><span style=\"font-family: verdana, geneva, sans-serif;\">En effet, une situation de pollution caus\u00e9e par les cimenteries bas\u00e9es dans la zone portuaire de Treichville inqui\u00e8te depuis un moment les populations, mettant \u00e0 mal leur sant\u00e9. Face aux nombreuses plaintes et sur instruction du Gouvernement, le Ministre en charge de l&#8217;Environnement a convoqu\u00e9 cette r\u00e9union d&#8217;urgence avec les entreprises concern\u00e9es, afin de trouver des solutions durables li\u00e9es aux impacts de leurs activit\u00e9s.<\/span><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: justify;\">\n<div dir=\"auto\"><span style=\"font-family: verdana, geneva, sans-serif;\">Le Centre Ivoirien Antipollution (CIAPOL), structure sous la tutelle du minist\u00e8re, a effectu\u00e9 diverses missions sur le terrain et formul\u00e9 des recommandations sp\u00e9cifiques aux entreprises pour att\u00e9nuer les impacts environnementaux. Cependant, ces recommandations n&#8217;ont manifestement pas \u00e9t\u00e9 mises en \u0153uvre, comme en t\u00e9moigne la persistance des probl\u00e8mes.<\/span><\/div>\n<div dir=\"auto\">\u00a0<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: justify;\">\n<div dir=\"auto\"><span style=\"font-family: verdana, geneva, sans-serif;\">\u00ab Environ 102 580 personnes sont impact\u00e9es par les activit\u00e9s des cimenteries dans la zone portuaire, la plus sensible en termes de pollution. Cette situation est due au nombre important d&#8217;activit\u00e9s de cimenteries au caract\u00e8re restreint de cette zone \u00bb, a soulign\u00e9 Professeur Ossey Yapo Bernard, le Directeur du CIAPOL.<\/span><\/div>\n<div dir=\"auto\">\u00a0<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: justify;\">\n<div dir=\"auto\"><span style=\"font-family: verdana, geneva, sans-serif;\">\u00c0 l&#8217;issue de cette rencontre, des directives claires ont \u00e9t\u00e9 donn\u00e9es par Monsieur le Ministre. Celles-ci partent des d\u00e9lais de mise \u00e0 niveau, o\u00f9 chacune des entreprises impliqu\u00e9es sera accompagn\u00e9e par les \u00e9quipes du minist\u00e8re, jusqu&#8217;\u00e0 leur fermeture pour non-conformit\u00e9 aux dispositions du code de l&#8217;environnement.<\/span><\/div>\n<div dir=\"auto\">\u00a0<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\" style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Le Ministre a tenu \u00e0 rassurer les populations impact\u00e9es que le Gouvernement se tient \u00e0 leurs c\u00f4t\u00e9s pour trouver une solution durable. Il en a profit\u00e9 pour saluer l\u2019engagement des services de la mairie de Treichville dans la r\u00e9solution de ce dossier.<\/span><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab On ne peut plus continuer \u00e0 mettre en balance la vie de la population avec des imp\u00e9ratifs \u00e9conomiques. Qu&#8217;est-ce que \u00e7a vaut d&#8217;avoir le prix du ciment bas si [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5531,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","pgc_sgb_lightbox_settings":""},"categories":[58],"tags":[],"post_folder":[59],"modified_by":"MINEDD","_links":{"self":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5530"}],"collection":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/comments?post=5530"}],"version-history":[{"count":1,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5530\/revisions"}],"predecessor-version":[{"id":5532,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5530\/revisions\/5532"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media\/5531"}],"wp:attachment":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media?parent=5530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/categories?post=5530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/tags?post=5530"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/post_folder?post=5530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}