{"id":5527,"date":"2024-07-09T15:09:46","date_gmt":"2024-07-09T15:09:46","guid":{"rendered":"https:\/\/did-dev.net\/mineddte\/?p=5527"},"modified":"2024-07-25T09:29:24","modified_gmt":"2024-07-25T09:29:24","slug":"comment-financer-ladaptation-au-changement-climatique-un-atelier-regional-pour-renforcer-les-capacites-des-pays-dafrique-francophone","status":"publish","type":"post","link":"https:\/\/did-dev.net\/mineddte\/comment-financer-ladaptation-au-changement-climatique-un-atelier-regional-pour-renforcer-les-capacites-des-pays-dafrique-francophone\/","title":{"rendered":"COMMENT FINANCER L\u2019ADAPTATION AU CHANGEMENT CLIMATIQUE\u00a0?\u00a0: UN ATELIER REGIONAL POUR RENFORCER LES CAPACITES DES PAYS D&#8217;AFRIQUE FRANCOPHONE"},"content":{"rendered":"<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\">\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-5528\" src=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/07\/Sans-titre-1-01-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1003\" srcset=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/07\/Sans-titre-1-01-scaled.jpg 2560w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/07\/Sans-titre-1-01-262x103.jpg 262w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/07\/Sans-titre-1-01-847x332.jpg 847w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/07\/Sans-titre-1-01-100x39.jpg 100w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/07\/Sans-titre-1-01-1536x602.jpg 1536w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/07\/Sans-titre-1-01-2048x803.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Le Directeur de la Coop\u00e9ration Internationale et de la Mobilisation des Financements, Monsieur YAO Marcel, a pr\u00e9sid\u00e9 le lancement de l\u2019atelier du programme r\u00e9gional de renforcement des capacit\u00e9s sur l\u2019acc\u00e8s aux financements de l\u2019adaptation au changement climatique en Afrique francophone du Nord et subsaharienne. C\u2019\u00e9tait le mardi 9 juillet 2024, Abidjan, Plateau.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Cet atelier a r\u00e9uni les partenaires techniques et financiers, les repr\u00e9sentants des Minist\u00e8res techniques des pays d\u2019Afrique francophone du Nord et subsaharienne et les entit\u00e9s nationales accr\u00e9dit\u00e9es \u00e0 un fonds. Il vise \u00e0 renforcer les capacit\u00e9s des d\u00e9l\u00e9gations en mati\u00e8re de financement innovant et de pr\u00e9paration de projets d\u2019adaptation au changement climatique. De m\u00eame, la prise en compte des principes d&#8217;\u00e9galit\u00e9 de genre et d&#8217;inclusion sociale (GESI) dans les projets d\u2019adaptation et l\u2019am\u00e9lioration des comp\u00e9tences en suivi, \u00e9valuation et gestion des risques sont au nombre des axes importants de l\u2019atelier.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Monsieur YAO Marcel a, au nom du ministre Assahor\u00e9 Konan Jacques, salu\u00e9 l\u2019organisation de cet atelier en terre ivoirienne, tout en soulignant son importance dans la planification et la mobilisation de financements.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">\u00ab Pour la mise en \u0153uvre des Contributions D\u00e9termin\u00e9es au niveau National de la C\u00f4te d\u2019Ivoire jusqu&#8217;en 2030, les ressources n\u00e9cessaires sont estim\u00e9es \u00e0 22 Milliards de dollars. Cet atelier de renforcement des capacit\u00e9s va permettre aux participants d\u2019adopter des approches pragmatiques et strat\u00e9giques pour planifier la mobilisation de financements des projets d\u2019adaptions de leur pays.\u00a0\u00bb, a-t-il indiqu\u00e9.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Madame Amanda Mckee, Directrice en charge du partage des connaissances et de l&#8217;apprentissage de l&#8217;unit\u00e9 de soutien au NDC Partnership, a particip\u00e9 \u00e0 l\u2019ouverture de cette rencontre. Selon elle, les pays en Afrique francophone et subsaharienne ont besoin d&#8217;appui pour avoir acc\u00e8s aux sources de financement climatique.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">\u00ab\u00a0C\u2019est pour cela que nous avons lanc\u00e9 ce programme de renforcement de capacit\u00e9s qui va permettre aux pays participants de renforcer et de d\u00e9velopper leurs comp\u00e9tences en adoptant des approches visant \u00e0 cr\u00e9er des conditions favorables pour augmenter la mobilisation du financement n\u00e9cessaire \u00e0 la mise en \u0153uvre de leurs priorit\u00e9s en mati\u00e8re d&#8217;adaptation au changement climatique.\u00a0\u00bb, a-t-elle soutenu.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Il faut noter que cette formation se d\u00e9roulera du 09 au 11 juillet 2024. Elle est \u00e0 l\u2019initiative de l&#8217;Unit\u00e9 de soutien du NDC Partnership, avec l\u2019appui du projet <strong><em>\u00ab\u00a0Action Climatique en Afrique du d\u00e9partement des Affaires Mondiales du Canada<\/em><\/strong>\u00a0\u00bb.<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le Directeur de la Coop\u00e9ration Internationale et de la Mobilisation des Financements, Monsieur YAO Marcel, a pr\u00e9sid\u00e9 le lancement de l\u2019atelier du programme r\u00e9gional de renforcement des capacit\u00e9s sur l\u2019acc\u00e8s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5528,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","pgc_sgb_lightbox_settings":""},"categories":[58],"tags":[],"post_folder":[59],"modified_by":"MINEDD","_links":{"self":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5527"}],"collection":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/comments?post=5527"}],"version-history":[{"count":2,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5527\/revisions"}],"predecessor-version":[{"id":5551,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5527\/revisions\/5551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media\/5528"}],"wp:attachment":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media?parent=5527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/categories?post=5527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/tags?post=5527"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/post_folder?post=5527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}