{"id":5399,"date":"2024-05-17T08:44:42","date_gmt":"2024-05-17T08:44:42","guid":{"rendered":"https:\/\/did-dev.net\/mineddte\/?p=5399"},"modified":"2024-06-04T08:58:54","modified_gmt":"2024-06-04T08:58:54","slug":"pollution-issue-des-sachets-plastiques-le-gouvernement-invite-les-acteurs-a-lapplication-du-decret","status":"publish","type":"post","link":"https:\/\/did-dev.net\/mineddte\/pollution-issue-des-sachets-plastiques-le-gouvernement-invite-les-acteurs-a-lapplication-du-decret\/","title":{"rendered":"POLLUTION ISSUE DES SACHETS PLASTIQUES : LE GOUVERNEMENT INVITE LES ACTEURS A L\u2019APPLICATION DU DECRET"},"content":{"rendered":"<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\">\n<div dir=\"auto\">\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-5401\" src=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/05\/DECHET-01-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1003\" srcset=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/05\/DECHET-01-scaled.jpg 2560w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/05\/DECHET-01-262x103.jpg 262w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/05\/DECHET-01-847x332.jpg 847w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/05\/DECHET-01-100x39.jpg 100w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/05\/DECHET-01-1536x602.jpg 1536w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/05\/DECHET-01-2048x803.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>Plusieurs repr\u00e9sentants issus de Minist\u00e8res techniques, des partenaires au d\u00e9veloppement, du secteur priv\u00e9 (producteurs, commer\u00e7ants, structures de valorisation), de la soci\u00e9t\u00e9 civile impliqu\u00e9es dans l\u2019industrie du plastique en C\u00f4te d\u2019Ivoire, ont pris part \u00e0 l\u2019atelier organis\u00e9 par le Minist\u00e8re de l&#8217;Environnement, du D\u00e9veloppement Durable et de la Transition \u00c9cologique, le 16 Mai 2024, au Plateau.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">L&#8217;identification des causes de la non-application du D\u00e9cret N\u00b02013-327 du 22 mai 2013, l\u2019exploration des \u00e9ventuelles alternatives au plastique, la r\u00e9organisation de la fili\u00e8re de collecte, de transport, de recyclage et d&#8217;\u00e9limination de cette mati\u00e8re ont \u00e9t\u00e9 au centre de l\u2019atelier.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Lors de la c\u00e9r\u00e9monie d\u2019ouverture, pr\u00e9sid\u00e9e par M. Assahor\u00e9 Konan Jacques, Ministre en charge de l\u2019Environnement, ce fut l\u2019occasion de r\u00e9it\u00e9rer l\u2019engagement de la C\u00f4te d\u2019Ivoire dans la lutte contre la pollution plastique. Il a soulign\u00e9 la synergie d\u2019actions souhait\u00e9e et la d\u00e9termination du Gouvernement \u00e0 faire appliquer le D\u00e9cret N\u00b02013-327 du 22 mai 2013, qui interdit la production, l\u2019importation, la commercialisation, la possession et l\u2019usage de sachets plastiques.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\"><em>\u00ab En vous conviant \u00e0 cette rencontre, je voudrais qu&#8217;ensemble nous puissions identifier les facteurs de blocage \u00e0 l&#8217;application du texte susmentionn\u00e9, proposer des solutions et \u00e9laborer une feuille de route consensuelle afin que d&#8217;un commun accord, nous parvenions \u00e0 l&#8217;application effective dudit texte \u00bb<\/em>, a-t-il affirm\u00e9 dans son allocution.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Depuis 2013, la C\u00f4te d\u2019Ivoire m\u00e8ne diverses initiatives visant \u00e0 limiter l&#8217;usage des sachets plastiques sur son territoire. Malgr\u00e9 des avanc\u00e9es notables dans certains secteurs tels que les p\u00e2tisseries, les pharmacies et les supermarch\u00e9s, o\u00f9 l&#8217;utilisation de sacs en papier kraft et de sacs r\u00e9utilisables a \u00e9t\u00e9 promue, un rel\u00e2chement a \u00e9t\u00e9 observ\u00e9 ces derni\u00e8res ann\u00e9es. En effet, le texte de loi s\u2019est heurt\u00e9 \u00e0 divers obstacles, rendant sa mise en \u0153uvre difficile.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Plus d&#8217;une d\u00e9cennie plus tard, la question de son application effective se pose avec acuit\u00e9 face au d\u00e9fi de la pollution plastique qui gagne du terrain. Le Ministre donne des chiffres sur le pic de pollution :<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">\u00ab<strong><em> La C\u00f4te d\u2019Ivoire produit chaque ann\u00e9e entre 40 000 et 100 000 tonnes de d\u00e9chets plastiques. 5 \u00e0 20 % sont recycl\u00e9s tandis que le reste est jet\u00e9 dans les rues, les d\u00e9p\u00f4ts sauvages ou br\u00fbl\u00e9 \u00e0 l\u2019air libre \u00bb<\/em><\/strong>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Face \u00e0 cette pollution galopante, l&#8217;une des voies \u00e0 explorer est celle de l&#8217;\u00e9conomie circulaire et du recyclage. \u00c0 ce niveau, M. Assahor\u00e9 a fait savoir que le Gouvernement se tiendrait aux c\u00f4t\u00e9s des entreprises qui s&#8217;engageront en faveur des secteurs cit\u00e9s ci-dessus.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Il a \u00e9galement partag\u00e9 la vision du Minist\u00e8re de l&#8217;Environnement, du D\u00e9veloppement Durable et de la Transition \u00c9cologique (MINEDDTE) qui est d&#8217;assainir la fili\u00e8re de la gestion des d\u00e9chets plastiques en C\u00f4te d\u2019Ivoire \u00e0 travers plusieurs actions. Il a cit\u00e9, entre autres, la cartographie des acteurs de la fili\u00e8re \u00e0 travers un projet de recensement des \u00e9co-entreprises de C\u00f4te d&#8217;Ivoire, la mise en place de centres de collecte et de recyclage des plastiques usag\u00e9s, la promotion des pratiques \u00e9cologiquement rationnelles, pour r\u00e9duire la pollution plastique. Autant de mesures qui devraient aboutir \u00e0 des niveaux de collecte et de recyclage plus \u00e9lev\u00e9s et contribuer \u00e0 l&#8217;\u00e9limination pure et simple de ces d\u00e9chets des rues.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Plusieurs pr\u00e9sentations et \u00e9changes ont marqu\u00e9 ce rendez-vous o\u00f9 chaque acteur a fait des contributions pour une strat\u00e9gie plus efficace et plus durable visant \u00e0 r\u00e9duire l&#8217;usage des sachets plastiques dans les modes de consommation.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">En mars 2022, la cinqui\u00e8me assembl\u00e9e des Nations unies pour l\u2019environnement a adopt\u00e9 une r\u00e9solution historique en vue de n\u00e9gocier, d\u2019ici fin 2024, un trait\u00e9 mondial de lutte contre la pollution plastique qui soit juridiquement contraignant et fond\u00e9 sur une approche globale couvrant l\u2019ensemble du cycle de vie des plastiques. Les Chefs d&#8217;\u00c9tat, les ministres de l&#8217;environnement et d&#8217;autres repr\u00e9sentants de 175 nations ont approuv\u00e9 cette r\u00e9solution historique. En tant que membre du Comit\u00e9 intergouvernemental de n\u00e9gociation (CIN) cr\u00e9\u00e9 \u00e0 cet effet, la C\u00f4te d&#8217;Ivoire a particip\u00e9 aux travaux de la 4\u00e8me r\u00e9union du CIN qui s&#8217;est achev\u00e9e \u00e0 Ottawa au Canada, le 29 avril 2024.<\/span><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Plusieurs repr\u00e9sentants issus de Minist\u00e8res techniques, des partenaires au d\u00e9veloppement, du secteur priv\u00e9 (producteurs, commer\u00e7ants, structures de valorisation), de la soci\u00e9t\u00e9 civile impliqu\u00e9es dans l\u2019industrie du plastique en C\u00f4te d\u2019Ivoire, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5401,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","pgc_sgb_lightbox_settings":""},"categories":[58],"tags":[],"post_folder":[59],"modified_by":"MINEDD","_links":{"self":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5399"}],"collection":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/comments?post=5399"}],"version-history":[{"count":1,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5399\/revisions"}],"predecessor-version":[{"id":5404,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5399\/revisions\/5404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media\/5401"}],"wp:attachment":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media?parent=5399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/categories?post=5399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/tags?post=5399"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/post_folder?post=5399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}