{"id":5360,"date":"2024-04-25T20:36:23","date_gmt":"2024-04-25T20:36:23","guid":{"rendered":"https:\/\/did-dev.net\/mineddte\/?p=5360"},"modified":"2024-05-13T12:15:07","modified_gmt":"2024-05-13T12:15:07","slug":"financements-verts-le-ministre-assahore-preside-la-signature-dun-protocole-de-cooperation-entre-la-brvm-et-le-gggi","status":"publish","type":"post","link":"https:\/\/did-dev.net\/mineddte\/financements-verts-le-ministre-assahore-preside-la-signature-dun-protocole-de-cooperation-entre-la-brvm-et-le-gggi\/","title":{"rendered":"FINANCEMENTS VERTS : LE MINISTRE ASSAHORE PRESIDE LA SIGNATURE D&#8217;UN PROTOCOLE DE COOPERATION ENTRE LA BRVM ET LE GGGI"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-5361\" src=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/04\/GGGI-01-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1003\" srcset=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/04\/GGGI-01-scaled.jpg 2560w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/04\/GGGI-01-262x103.jpg 262w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/04\/GGGI-01-847x332.jpg 847w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/04\/GGGI-01-100x39.jpg 100w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/04\/GGGI-01-1536x602.jpg 1536w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/04\/GGGI-01-2048x803.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Un protocole de coop\u00e9ration a \u00e9t\u00e9 sign\u00e9 entre la Bourse R\u00e9gionale des Valeurs Mobili\u00e8res (BRVM) et le Global Green Growth Institute (GGGI) le 25 avril 2024, \u00e0 la salle des cotations de la BRVM. Cette c\u00e9r\u00e9monie, pr\u00e9sid\u00e9e par M. Assahor\u00e9 Konan Jacques, Ministre de l&#8217;Environnement, du D\u00e9veloppement Durable et de la Transition \u00c9cologique, a r\u00e9uni des repr\u00e9sentants de la CEDEAO, de la Commission de l&#8217;UEMOA et du secteur priv\u00e9.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">L&#8217;accord vise principalement \u00e0 promouvoir l&#8217;acc\u00e8s aux financements climatiques et \u00e0 encourager l&#8217;\u00e9mission d&#8217;obligations vertes dans l&#8217;espace de l&#8217;Union \u00c9conomique et Mon\u00e9taire Ouest-africaine, tout en renfor\u00e7ant les comp\u00e9tences des acteurs financiers r\u00e9gionaux en mati\u00e8re de finance durable.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Assahor\u00e9 a exprim\u00e9 son enthousiasme pour ce partenariat : <em>\u00ab Je salue la signature de ce partenariat entre la BRVM et le GGGI qui d\u00e9montre que le march\u00e9 financier ouest-africain est d\u00e9termin\u00e9 \u00e0 adopter des sources de financement innovantes telles que les obligations vertes. Ces derni\u00e8res peuvent soutenir le d\u00e9veloppement durable et contribuer \u00e0 freiner le changement climatique \u00bb<\/em>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Il a indiqu\u00e9 que ce partenariat fournira un cadre de collaboration conforme \u00e0 l\u2019Agenda 2030 sur les Objectifs de D\u00e9veloppement Durable (ODD) et \u00e0 l\u2019Accord de Paris sur le climat. <em>\u00ab Je suis convaincu que le GGGI et la BRVM d\u00e9velopperont des programmes de sensibilisation et d\u2019\u00e9ducation pour promouvoir les opportunit\u00e9s li\u00e9es aux obligations vertes \u00bb,<\/em> a-t-il souhait\u00e9.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Le Dr EDOH Kossi Amenounve, Directeur g\u00e9n\u00e9ral de la BRVM et Monsieur Kyung Nam Shin, Directeur G\u00e9n\u00e9ral Adjoint du GGGI ont paraph\u00e9 cet accord important pour la sous-r\u00e9gion.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">La C\u00f4te d&#8217;Ivoire, membre officiel du GGGI depuis le 24 septembre 2020, s&#8217;engage fermement en faveur d&#8217;une croissance verte align\u00e9e sur ses objectifs de r\u00e9duction des \u00e9missions de gaz \u00e0 effet de serre et de r\u00e9silience climatique. Les obligations vertes, instruments financiers d\u00e9di\u00e9s au financement de projets environnementaux, sont au c\u0153ur de cette strat\u00e9gie. Elles permettent de canaliser des fonds vers des initiatives \u00e9coresponsables telles que les \u00e9nergies renouvelables, l&#8217;efficacit\u00e9 \u00e9nerg\u00e9tique, ou encore la gestion durable des ressources naturelles.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Ces instruments offrent des avantages mutuels : pour les investisseurs, ils repr\u00e9sentent une chance d&#8217;aligner leurs portefeuilles avec leurs convictions environnementales, et pour les \u00e9metteurs, ils sont un moyen d&#8217;am\u00e9liorer leur image et d&#8217;attirer des capitaux conscients des enjeux \u00e9cologiques.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Le GGGI, acteur cl\u00e9 de la croissance verte, \u0153uvre \u00e0 catalyser les investissements dans des projets bas carbone, \u00e0 \u00e9laborer des politiques de croissance verte adapt\u00e9es et \u00e0 accompagner les pays dans leur transition \u00e9cologique. En collaboration avec diverses parties prenantes, le GGGI identifie les actions prioritaires, mobilise des financements et renforce les capacit\u00e9s pour une \u00e9conomie durable.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un protocole de coop\u00e9ration a \u00e9t\u00e9 sign\u00e9 entre la Bourse R\u00e9gionale des Valeurs Mobili\u00e8res (BRVM) et le Global Green Growth Institute (GGGI) le 25 avril 2024, \u00e0 la salle des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5361,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","pgc_sgb_lightbox_settings":""},"categories":[58],"tags":[],"post_folder":[59],"modified_by":"MINEDD","_links":{"self":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5360"}],"collection":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/comments?post=5360"}],"version-history":[{"count":2,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5360\/revisions"}],"predecessor-version":[{"id":5379,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5360\/revisions\/5379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media\/5361"}],"wp:attachment":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media?parent=5360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/categories?post=5360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/tags?post=5360"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/post_folder?post=5360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}