{"id":5345,"date":"2024-04-21T09:21:20","date_gmt":"2024-04-21T09:21:20","guid":{"rendered":"https:\/\/did-dev.net\/mineddte\/?p=5345"},"modified":"2024-04-29T09:46:37","modified_gmt":"2024-04-29T09:46:37","slug":"mise-en-oeuvre-du-code-de-lenvironnement-le-ministre-assahore-sollicite-les-33-prefets-de-region-de-la-cote-divoire","status":"publish","type":"post","link":"https:\/\/did-dev.net\/mineddte\/mise-en-oeuvre-du-code-de-lenvironnement-le-ministre-assahore-sollicite-les-33-prefets-de-region-de-la-cote-divoire\/","title":{"rendered":"MISE EN \u0152UVRE DU CODE DE L\u2019ENVIRONNEMENT : LE MINISTRE ASSAHORE SOLLICITE LES 33 PREFETS DE REGION DE LA COTE D\u2019IVOIRE"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-5346\" src=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/04\/Sans-titre-1-01-3-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1003\" srcset=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/04\/Sans-titre-1-01-3-scaled.jpg 2560w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/04\/Sans-titre-1-01-3-262x103.jpg 262w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/04\/Sans-titre-1-01-3-847x332.jpg 847w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/04\/Sans-titre-1-01-3-100x39.jpg 100w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/04\/Sans-titre-1-01-3-1536x602.jpg 1536w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/04\/Sans-titre-1-01-3-2048x803.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Le Minist\u00e8re de l\u2019Environnement, du D\u00e9veloppement Durable et de la Transition s\u2019est engag\u00e9 \u00e0 mettre en \u0153uvre le nouveau Code de l&#8217;Environnement, promulgu\u00e9 en 2023 par le Gouvernement. Il a organis\u00e9, dans ce cadre, un important atelier \u00e0 Bouak\u00e9, le 20 avril 2024. L&#8217;\u00e9v\u00e9nement a r\u00e9uni les Pr\u00e9fets de r\u00e9gion pour discuter des nouvelles dispositions de ce nouvel instrument juridique et de la contribution des Autorit\u00e9s Pr\u00e9fectorales aux activit\u00e9s d\u2019\u00e9valuations environnementales.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Pr\u00e9sidant la rencontre, le Ministre ASSAHORE Konan Jacques a soulign\u00e9 l\u2019int\u00e9r\u00eat de renforcer les capacit\u00e9s des Autorit\u00e9s Pr\u00e9fectorales, acteurs majeurs au niveau des activit\u00e9s d\u2019\u00e9valuations, notamment l&#8217;enqu\u00eate publique et l&#8217;examen technique des rapports d&#8217;\u00e9tudes. <em>\u00ab La lutte que nous menons aujourd\u2019hui, nous la menons pour nos enfants. Nous voulons vous pr\u00e9senter les d\u00e9fis \u00e0 relever afin de solliciter votre soutien et votre accompagnement pour r\u00e9ussir ce combat \u00bb<\/em>, a-t-il d\u00e9clar\u00e9. Il a insist\u00e9 sur leurs capacit\u00e9s \u00e0 relayer les informations en pr\u00e9cisant, par ailleurs qu\u2019un tel combat ne saurait prosp\u00e9rer sans leur implication, d\u2019o\u00f9 l\u2019organisation de l\u2019atelier.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Monsieur Assahor\u00e9 a \u00e9galement exprim\u00e9 la volont\u00e9 pour son Minist\u00e8re de voir le code de l\u2019environnement partag\u00e9 avec l\u2019ensemble du corps pr\u00e9fectoral. <em>\u00ab Le Minist\u00e8re souhaite que le code de l\u2019environnement soit vulgaris\u00e9 \u00e0 l\u2019ensemble du corps pr\u00e9fectoral afin que vous soyez notre relais en partageant les dispositions nouvelles avec les populations dans vos localit\u00e9s respectives \u00bb,<\/em> a-t-il ajout\u00e9.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">D\u2019\u00e9minentes personnalit\u00e9s de la R\u00e9gion du Gb\u00eak\u00ea, telles que Monsieur Jean-Claude Kouassi, Ministre Gouverneur du District Autonome de la Vall\u00e9e du Bandama, et Madame Korotoumou Diomand\u00e9, 4e Vice-Pr\u00e9sidente du Conseil R\u00e9gional du Gb\u00eak\u00ea, ont pris la parole pour indiquer l&#8217;urgence de sensibiliser aux enjeux environnementaux. Ils ont exhort\u00e9 \u00e0 une adoption g\u00e9n\u00e9ralis\u00e9e du Code de l&#8217;Environnement \u00e0 travers toutes les strates de la soci\u00e9t\u00e9.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">L&#8217;atelier a \u00e9t\u00e9 marqu\u00e9 par diverses pr\u00e9sentations, notamment sur la Strat\u00e9gie nationale de lutte contre le changement climatique par le Docteur \u00c9ric Assamoi. Il a montr\u00e9 que le plan d&#8217;action climatique de la C\u00f4te d&#8217;Ivoire repose sur trois piliers essentiels : l\u2019att\u00e9nuation, l\u2019adaptation et le financement. Ainsi, la strat\u00e9gie vise une r\u00e9duction significative de 30,41% des \u00e9missions de gaz \u00e0 effet de serre d&#8217;ici 2030, tout en renfor\u00e7ant la r\u00e9silience du pays dans cinq secteurs prioritaires : ressources en eau, agriculture, foresterie, zones c\u00f4ti\u00e8res et sant\u00e9. Pour la mise en \u0153uvre de ces mesures, le pays pr\u00e9voit de mobiliser des financements consid\u00e9rables, estim\u00e9s \u00e0 environ 12 000 milliards de francs CFA.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">En attendant, le Gouvernement ivoirien a pris plusieurs mesures pour r\u00e9pondre efficacement aux enjeux. Ces mesures incluent une augmentation de 45% de la part des \u00e9nergies renouvelables dans le mix \u00e9nerg\u00e9tique, une augmentation de 20% de l&#8217;efficacit\u00e9 \u00e9nerg\u00e9tique dans le secteur du b\u00e2timent, une augmentation de 10% de la part des v\u00e9hicules \u00e9lectriques d&#8217;ici \u00e0 2030, ainsi que la construction de 12 d\u00e9charges modernes \u00e0 l&#8217;int\u00e9rieur du pays, avec une capacit\u00e9 de traitement \u00e9valu\u00e9e \u00e0 1 000 000 tonnes par an.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Le Conseiller Technique Kouadio Georges a effectu\u00e9 une revue d\u00e9taill\u00e9e du nouveau Code de l&#8217;Environnement, pr\u00e9sentant ainsi aux Autorit\u00e9s Pr\u00e9fectorales les mesures innovantes visant \u00e0 renforcer la protection de l&#8217;environnement et \u00e0 relever les d\u00e9fis \u00e9cologiques. Parmi celles-ci, il faut citer le &#8220;principe de non-r\u00e9gression&#8221; engageant l&#8217;\u00c9tat \u00e0 pr\u00e9venir tout recul dans les politiques environnementales. Ensuite, la &#8220;responsabilit\u00e9 \u00e9largie du producteur&#8221; impose aux fabricants, distributeurs et importateurs de prendre en charge la gestion des d\u00e9chets g\u00e9n\u00e9r\u00e9s par leurs produits. Le texte consacre le &#8220;droit \u00e0 l&#8217;\u00e9ducation environnementale&#8221;, incitant l&#8217;\u00c9tat, les collectivit\u00e9s territoriales, le secteur priv\u00e9 et la soci\u00e9t\u00e9 civile \u00e0 promouvoir la sensibilisation, la formation et la recherche-d\u00e9veloppement en mati\u00e8re d&#8217;environnement. Il vient r\u00e9pondre aux enjeux majeurs tels que les changements climatiques, la diversit\u00e9 biologique, la pr\u00e9servation des montagnes et des mangroves, ainsi que la gestion \u00e9largie des d\u00e9chets. Des mesures sp\u00e9cifiques sont propos\u00e9es pour promouvoir les \u00e9nergies renouvelables, pr\u00e9venir la biopiraterie et pr\u00e9server les \u00e9cosyst\u00e8mes fragiles.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">De nouveaux outils de gestion sont introduits, renfor\u00e7ant les outils existants. L&#8217;introduction de l&#8217;\u00c9tude d&#8217;Impact Environnemental et Social (EIES), de l&#8217;Audit Environnemental Social (AES) et de l&#8217;\u00c9valuation Environnementale et Sociale Strat\u00e9gique (EESS) mettent l&#8217;accent sur l&#8217;aspect social et la participation communautaire.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Au niveau institutionnel, une Police de l&#8217;Environnement sera cr\u00e9\u00e9e pour veiller au respect de la r\u00e9glementation. De plus, une nouvelle Agence, dot\u00e9e de personnalit\u00e9 juridique et d&#8217;autonomie financi\u00e8re, remplacera l&#8217;Agence Nationale de l&#8217;Environnement pour une gestion plus efficace.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Le Code pr\u00e9voit \u00e9galement un renforcement des sanctions pour les infractions environnementales, d\u00e9montrant la d\u00e9termination de la C\u00f4te d&#8217;Ivoire \u00e0 prot\u00e9ger ses ressources naturelles. Enfin, la cons\u00e9cration du pr\u00e9judice \u00e9cologique dans la l\u00e9gislation permettra \u00e0 toute personne affect\u00e9e de d\u00e9clencher des actions en r\u00e9paration et de recevoir des d\u00e9dommagements en cas d&#8217;infraction environnementale.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Quant au Directeur de l&#8217;Agence Nationale de l&#8217;Environnement (ANDE), M. Bouaky Ernest, il a pr\u00e9sent\u00e9 le bilan de la participation des Autorit\u00e9s Pr\u00e9fectorales aux activit\u00e9s d&#8217;\u00e9valuations environnementales. Cette \u00e9tape a \u00e9t\u00e9 l\u2019occasion de proposer un nouveau cadre de collaboration entre le Minist\u00e8re et le corps pr\u00e9fectoral sur les activit\u00e9s d\u2019\u00e9valuations environnementales.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Une copie du nouveau Code de l&#8217;Environnement a \u00e9t\u00e9 remise aux Autorit\u00e9s Pr\u00e9fectorales qui ont salu\u00e9 l\u2019initiative de cette rencontre, formul\u00e9 des recommandations fortes et se sont engag\u00e9es \u00e0 poursuivre les efforts de pr\u00e9servation de l\u2019environnement, men\u00e9s au quotidien dans leurs localit\u00e9s respectives.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Minist\u00e8re de l\u2019Environnement, du D\u00e9veloppement Durable et de la Transition s\u2019est engag\u00e9 \u00e0 mettre en \u0153uvre le nouveau Code de l&#8217;Environnement, promulgu\u00e9 en 2023 par le Gouvernement. Il a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5346,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","pgc_sgb_lightbox_settings":""},"categories":[58],"tags":[],"post_folder":[59],"modified_by":"MINEDD","_links":{"self":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5345"}],"collection":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/comments?post=5345"}],"version-history":[{"count":2,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5345\/revisions"}],"predecessor-version":[{"id":5348,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5345\/revisions\/5348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media\/5346"}],"wp:attachment":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media?parent=5345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/categories?post=5345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/tags?post=5345"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/post_folder?post=5345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}