{"id":5267,"date":"2024-03-13T08:25:04","date_gmt":"2024-03-13T08:25:04","guid":{"rendered":"https:\/\/did-dev.net\/mineddte\/?p=5267"},"modified":"2024-03-25T10:04:45","modified_gmt":"2024-03-25T10:04:45","slug":"mortalite-de-poissons-dans-la-baie-de-bietry-le-ministre-de-lenvironnement-devoile-les-conclusions-des-enquetes","status":"publish","type":"post","link":"https:\/\/did-dev.net\/mineddte\/mortalite-de-poissons-dans-la-baie-de-bietry-le-ministre-de-lenvironnement-devoile-les-conclusions-des-enquetes\/","title":{"rendered":"MORTALITE DE POISSONS DANS LA BAIE DE BIETRY : LE MINISTRE DE L&#8217;ENVIRONNEMENT DEVOILE LES CONCLUSIONS DES ENQUETES"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-5268\" src=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/03\/Sans-titre-2-01-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1003\" srcset=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/03\/Sans-titre-2-01-scaled.jpg 2560w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/03\/Sans-titre-2-01-262x103.jpg 262w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/03\/Sans-titre-2-01-847x332.jpg 847w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/03\/Sans-titre-2-01-100x39.jpg 100w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/03\/Sans-titre-2-01-1536x602.jpg 1536w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/03\/Sans-titre-2-01-2048x803.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Lors d&#8217;une conf\u00e9rence de presse tenue \u00e0 son Cabinet le 12 mars 2024, le Ministre de l&#8217;Environnement, du D\u00e9veloppement Durable et de la Transition \u00c9cologique, Assahor\u00e9 Konan Jacques a r\u00e9v\u00e9l\u00e9 les r\u00e9sultats des enqu\u00eates men\u00e9es par le Centre Ivoirien Antipollution (CIAPOL) sur la r\u00e9cente mortalit\u00e9 soudaine de poissons dans la Baie de Bi\u00e9try.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Le Ministre a soulign\u00e9 que les enqu\u00eates ont \u00e9tabli que cette trag\u00e9die \u00e9tait due \u00e0 un ph\u00e9nom\u00e8ne de pollution de masse d&#8217;origine chimique, entra\u00eenant un appauvrissement en oxyg\u00e8ne dans le milieu aquatique.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">\u00ab Aujourd\u2019hui les services techniques ont fini leur travail, ils sont venus l\u00e0 pour rassurer les populations et leur dire que ce qui s&#8217;est pass\u00e9 est li\u00e9 \u00e0 un ph\u00e9nom\u00e8ne de pollution de masse. Habituellement cette zone connait ce genre d&#8217;\u00e9v\u00e9nements mais cette fois-ci, l&#8217;ampleur a \u00e9t\u00e9 telle que tout le monde a \u00e9t\u00e9 appel\u00e9\u00a0\u00bb, a-t-il d\u00e9clar\u00e9.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Il a expliqu\u00e9 que les recherches se poursuivent pour identifier pr\u00e9cis\u00e9ment la source de cette pollution, qui pourrait \u00eatre d&#8217;origine domestique ou industrielle. Ces recherches en cours visent \u00e0 prendre des mesures pour pr\u00e9venir de nouveaux incidents similaires dans la lagune Ebri\u00e9.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Le Ministre a \u00e9galement lanc\u00e9 un appel \u00e0 l&#8217;\u00e9cocitoyennet\u00e9, soulignant l&#8217;importance de prot\u00e9ger la lagune et de pr\u00e9server son \u00e9cosyst\u00e8me fragile. Il a exhort\u00e9 la population \u00e0 adopter des comportements respectueux de l&#8217;environnement et \u00e0 soutenir les efforts visant \u00e0 restaurer la sant\u00e9 de la baie.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">\u00ab Je voudrais demander aux ivoiriens de prendre conscience de l&#8217;importance \u00e9cologique de ce plan d&#8217;eau que la nature nous a donn\u00e9. Nous devons en prendre soin pour ne pas qu\u2019il perde sa fonction \u00e9cologique originelle. Ayons des gestes \u00e9co-citoyens, prot\u00e9geons la lagune \u00bb, a-t-il exhort\u00e9.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Au nombre des recommandations fortes des r\u00e9sultats de l\u2019enqu\u00eate, il faut citer, l&#8217;am\u00e9lioration des infrastructures d&#8217;assainissement, la d\u00e9pollution des Baies d\u2019Abidjan, y compris le canal d\u2019Anoumabo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">En attendant la fin des op\u00e9rations en cours, une zone temporairement interdite de p\u00eache a \u00e9t\u00e9 \u00e9tablie pour prot\u00e9ger les ressources restantes et permettre la restauration de l&#8217;\u00e9cosyst\u00e8me affect\u00e9.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lors d&#8217;une conf\u00e9rence de presse tenue \u00e0 son Cabinet le 12 mars 2024, le Ministre de l&#8217;Environnement, du D\u00e9veloppement Durable et de la Transition \u00c9cologique, Assahor\u00e9 Konan Jacques a r\u00e9v\u00e9l\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","pgc_sgb_lightbox_settings":""},"categories":[58],"tags":[],"post_folder":[59],"modified_by":"MINEDD","_links":{"self":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5267"}],"collection":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/comments?post=5267"}],"version-history":[{"count":2,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5267\/revisions"}],"predecessor-version":[{"id":5300,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5267\/revisions\/5300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media\/5268"}],"wp:attachment":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media?parent=5267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/categories?post=5267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/tags?post=5267"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/post_folder?post=5267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}