{"id":5243,"date":"2024-03-06T09:14:36","date_gmt":"2024-03-06T09:14:36","guid":{"rendered":"https:\/\/did-dev.net\/mineddte\/?p=5243"},"modified":"2024-03-07T13:44:19","modified_gmt":"2024-03-07T13:44:19","slug":"mortalite-brusque-de-poissons-dans-la-baie-de-bietry-les-ministres-assahore-konan-jacques-et-sidi-tiemoko-toure-se-rendent-sur-place-pour-evaluer-la-situation","status":"publish","type":"post","link":"https:\/\/did-dev.net\/mineddte\/mortalite-brusque-de-poissons-dans-la-baie-de-bietry-les-ministres-assahore-konan-jacques-et-sidi-tiemoko-toure-se-rendent-sur-place-pour-evaluer-la-situation\/","title":{"rendered":"MORTALITE BRUSQUE DE POISSONS DANS LA BAIE DE BIETRY : LES MINISTRES ASSAHORE KONAN JACQUES ET SIDI TIEMOKO TOURE SE RENDENT SUR PLACE POUR EVALUER LA SITUATION"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-5244\" src=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/03\/Sans-titre-1-01-2-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1003\" srcset=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/03\/Sans-titre-1-01-2-scaled.jpg 2560w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/03\/Sans-titre-1-01-2-262x103.jpg 262w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/03\/Sans-titre-1-01-2-847x332.jpg 847w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/03\/Sans-titre-1-01-2-100x39.jpg 100w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/03\/Sans-titre-1-01-2-1536x602.jpg 1536w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2024\/03\/Sans-titre-1-01-2-2048x803.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>Une pr\u00e9occupation environnementale majeure a r\u00e9cemment \u00e9merg\u00e9 sur la lagune Ebri\u00e9, plus pr\u00e9cis\u00e9ment dans la baie de Bi\u00e9try, o\u00f9 des mortalit\u00e9s brusques de poissons ont \u00e9t\u00e9 observ\u00e9es. Cette situation alarmante a suscit\u00e9 une r\u00e9ponse imm\u00e9diate des autorit\u00e9s ivoiriennes, avec une mission d&#8217;enqu\u00eate men\u00e9e sur le terrain le mardi 5 mars 2024.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Mandat\u00e9s par le Premier Ministre, les Ministres Assahor\u00e9 Konan Jacques, en charge de l&#8217;Environnement, et Sidi Ti\u00e9moko Tour\u00e9, responsable des Ressources animales et halieutiques, se sont rendus sur place pour \u00e9valuer la situation de premi\u00e8re main.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Les constatations initiales effectu\u00e9es par le Centre Ivoirien Anti-Pollution (CIAPOL) et les Services de l\u2019Etat ont r\u00e9v\u00e9l\u00e9 des hypoth\u00e8ses pr\u00e9occupantes. Celles-ci pointent du doigt un niveau tr\u00e8s bas d&#8217;oxyg\u00e8ne dissout dans la lagune. Le manque d&#8217;oxyg\u00e8ne dans ce milieu aquatique serait d\u00fb \u00e0 l&#8217;accumulation de d\u00e9chets organiques et \u00e0 la pollution des eaux de surface, aggrav\u00e9es par les pluies r\u00e9centes.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">En effet, le ph\u00e9nom\u00e8ne de mortalit\u00e9 des poissons semble se r\u00e9p\u00e9ter p\u00e9riodiquement chaque ann\u00e9e, notamment au d\u00e9but de la saison des pluies, lorsqu&#8217;une quantit\u00e9 importante de d\u00e9chets et de polluants est entra\u00een\u00e9e dans la lagune par les eaux de ruissellement. Cette pollution est souvent li\u00e9e aux activit\u00e9s anthropiques et les d\u00e9versements directs dans les cours d&#8217;eau.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Les esp\u00e8ces touch\u00e9es sont principalement les carpes et les tilapias, sensibles \u00e0 la pollution et \u00e0 la baisse du taux d&#8217;oxyg\u00e8ne dans l&#8217;eau.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Dans ce contexte, les ministres ont exhort\u00e9 les communaut\u00e9s locales \u00e0 promouvoir des pratiques durables pour pr\u00e9server leur sant\u00e9, ainsi que celle de l&#8217;\u00e9cosyst\u00e8me marin. Ils ont par ailleurs, invit\u00e9 les populations \u00e0 ne pas pratiquer de p\u00eache et ne pas consommer les poissons issus de cette baie, jusqu\u2019\u00e0 nouvel ordre.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Des mesures concr\u00e8tes, telles que l&#8217;am\u00e9lioration des infrastructures d&#8217;assainissement, la d\u00e9pollution des baies sont \u00e9galement envisag\u00e9es pour pr\u00e9venir de telles crises \u00e0 l&#8217;avenir. C\u2019est \u00e0 juste titre que les Ministres Assahor\u00e9 Konan Jacques et Bouak\u00e9 Fofana ont tenu une r\u00e9union avec les \u00e9lus locaux et les chefs coutumiers de la Commune de Marcory le lundi 04 mars 2024, \u00e0 la chefferie d&#8217;Anoumabo. Cette rencontre a permis d\u2019informer les populations sur les enjeux de la d\u00e9cision du Gouvernement de lancer, dans les jours \u00e0 venir, les travaux de restauration du canal d\u2019Anoumabo.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une pr\u00e9occupation environnementale majeure a r\u00e9cemment \u00e9merg\u00e9 sur la lagune Ebri\u00e9, plus pr\u00e9cis\u00e9ment dans la baie de Bi\u00e9try, o\u00f9 des mortalit\u00e9s brusques de poissons ont \u00e9t\u00e9 observ\u00e9es. Cette situation alarmante [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5244,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","pgc_sgb_lightbox_settings":""},"categories":[58],"tags":[],"post_folder":[59],"modified_by":"MINEDD","_links":{"self":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5243"}],"collection":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/comments?post=5243"}],"version-history":[{"count":1,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5243\/revisions"}],"predecessor-version":[{"id":5245,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/5243\/revisions\/5245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media\/5244"}],"wp:attachment":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media?parent=5243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/categories?post=5243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/tags?post=5243"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/post_folder?post=5243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}