{"id":4941,"date":"2023-12-22T14:37:40","date_gmt":"2023-12-22T14:37:40","guid":{"rendered":"https:\/\/did-dev.net\/mineddte\/?p=4941"},"modified":"2023-12-26T10:01:00","modified_gmt":"2023-12-26T10:01:00","slug":"plateforme-nationale-genre-et-changement-climatique-la-cote-divoire-partage-son-experience-avec-la-sous-region","status":"publish","type":"post","link":"https:\/\/did-dev.net\/mineddte\/plateforme-nationale-genre-et-changement-climatique-la-cote-divoire-partage-son-experience-avec-la-sous-region\/","title":{"rendered":"PLATEFORME NATIONALE GENRE ET CHANGEMENT CLIMATIQUE\u00a0: LA COTE D\u2019IVOIRE PARTAGE SON EXP\u00c9RIENCE AVEC LA SOUS-R\u00c9GION"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-4942\" src=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-6-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1003\" srcset=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-6-scaled.jpg 2560w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-6-262x103.jpg 262w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-6-847x332.jpg 847w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-6-100x39.jpg 100w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-6-1536x602.jpg 1536w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-6-2048x803.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>Le 20 d\u00e9cembre 2023, \u00e0 la salle de conf\u00e9rence du Minist\u00e8re de l\u2019Environnement du D\u00e9veloppement Durable et de la Transition Ecologique, sise \u00e0 la riviera Bonoumin, deux d\u00e9l\u00e9gations des pays fr\u00e8res du S\u00e9n\u00e9gal et de la Centrafrique se sont mobilis\u00e9es pour un important partage d\u2019exp\u00e9rience avec la plateforme nationale genre et changement climatique (PNGGC) de la C\u00f4te d\u2019Ivoire.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Les acteurs se sont impr\u00e9gn\u00e9s des avanc\u00e9es relatives \u00e0 l\u2019int\u00e9gration du genre dans le processus du Plan National d\u2019Adaptation (PNA) de la C\u00f4te d\u2019Ivoire. Aussi, ont-ils fait le bilan de leurs activit\u00e9s au titre de l\u2019ann\u00e9e 2023.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\"><strong>JEAN ANAMAN DOUGLASS<\/strong>,\u00a0Coordonnateur du Plan National d&#8217;Adaptation (PNA) est centr\u00e9 sur cinq axes prioritaires et 351 indicateurs. A en croire le Coordonnateur, ces indicateurs ont permis l\u2019implication des hommes et des femmes, des filles et des gar\u00e7ons afin d\u2019apporter des corrections certaines \u00e0 des in\u00e9galit\u00e9s de genre observ\u00e9es.\u00a0\u00a0\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Plusieurs membres issus des minist\u00e8res techniques, du secteur priv\u00e9, de la soci\u00e9t\u00e9 civile et les diff\u00e9rentes d\u00e9l\u00e9gations qui ont rehauss\u00e9 de leur pr\u00e9sence au nombre desquels Madame <strong>AMOUDOU n\u00e9e SIDI Mariam Catherine<\/strong>, Directrice en charge de l\u2019adaptation \/point focal genre et changement climatique de la r\u00e9publique centrafricaine et Madame <strong>SALL ND\u00c8YE ROKKYA<\/strong> du Minist\u00e8re de l\u2019Environnement, du D\u00e9veloppement Durable et de la Transition Ecologique du S\u00e9n\u00e9gal.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Notons que l\u2019adaptation changement climatique repr\u00e9sente une r\u00e9ponse cruciale aux changements climatiques, lesquels ont des impacts significatifs tant sur les ressources naturelles que sur les activit\u00e9s humaines et la population. De tels effets varient en fonction des r\u00e9gions, des cultures, de l&#8217;\u00e9ducation, des croyances et du genre, engendrant des cons\u00e9quences diff\u00e9renci\u00e9es entre hommes et femmes en raison des in\u00e9galit\u00e9s de genre\u00a0pr\u00e9existantes.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 20 d\u00e9cembre 2023, \u00e0 la salle de conf\u00e9rence du Minist\u00e8re de l\u2019Environnement du D\u00e9veloppement Durable et de la Transition Ecologique, sise \u00e0 la riviera Bonoumin, deux d\u00e9l\u00e9gations des pays [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4942,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","pgc_sgb_lightbox_settings":""},"categories":[58],"tags":[],"post_folder":[59],"modified_by":"MINEDD","_links":{"self":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/4941"}],"collection":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/comments?post=4941"}],"version-history":[{"count":1,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/4941\/revisions"}],"predecessor-version":[{"id":4943,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/4941\/revisions\/4943"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media\/4942"}],"wp:attachment":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media?parent=4941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/categories?post=4941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/tags?post=4941"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/post_folder?post=4941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}