{"id":4906,"date":"2023-12-10T10:36:44","date_gmt":"2023-12-10T10:36:44","guid":{"rendered":"https:\/\/did-dev.net\/mineddte\/?p=4906"},"modified":"2023-12-22T15:31:27","modified_gmt":"2023-12-22T15:31:27","slug":"cop28-a-mi-parcours-de-sa-participation-la-cote-divoire-signe-un-engagement-concret-des-acquis-significatifs-et-des-perspectives-ambitieuses","status":"publish","type":"post","link":"https:\/\/did-dev.net\/mineddte\/cop28-a-mi-parcours-de-sa-participation-la-cote-divoire-signe-un-engagement-concret-des-acquis-significatifs-et-des-perspectives-ambitieuses\/","title":{"rendered":"COP28 : A MI-PARCOURS DE SA PARTICIPATION, LA COTE D\u2019IVOIRE SIGNE UN ENGAGEMENT CONCRET, DES ACQUIS SIGNIFICATIFS ET DES PERSPECTIVES AMBITIEUSES"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-4909\" src=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-2-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1003\" srcset=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-2-scaled.jpg 2560w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-2-262x103.jpg 262w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-2-847x332.jpg 847w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-2-100x39.jpg 100w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-2-1536x602.jpg 1536w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-2-2048x803.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Depuis le 29 novembre 2023, la C\u00f4te d&#8217;Ivoire participe activement \u00e0 la 28e Conf\u00e9rence des Parties sur le climat (COP28) \u00e0 Duba\u00ef, marquant son engagement concret dans la lutte mondiale contre les changements climatiques.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Le Ministre de l&#8217;Environnement, Jacques Assahor\u00e9 KONAN, a r\u00e9cemment partag\u00e9 un bilan \u00e0 mi-parcours lors d&#8217;un point de presse au Pavillon de la C\u00f4te d&#8217;Ivoire \u00e0 Duba\u00ef, le 9 d\u00e9cembre 2023.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Dans ses propos, il est revenu sur la participation ivoirienne qui a \u00e9t\u00e9 minutieuse et diversifi\u00e9e, impliquant la Pr\u00e9sidence de la R\u00e9publique, des institutions, le secteur priv\u00e9, les collectivit\u00e9s territoriales, et d&#8217;autres acteurs. L&#8217;approche collaborative a \u00e9t\u00e9 soulign\u00e9e, avec certains participants financ\u00e9s par des partenaires techniques et financiers.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">En poursuivant, Jacques Assahor\u00e9 KONAN a rappel\u00e9 que les attentes de la C\u00f4te d&#8217;Ivoire \u00e0 la COP28 \u00e9taient ax\u00e9es sur quatre points strat\u00e9giques, notamment la mobilisation des ressources financi\u00e8res, l&#8217;accroissement de la coop\u00e9ration Sud-Sud et Nord-Sud, l&#8217;effectivit\u00e9 du transfert de technologies, et l&#8217;op\u00e9rationnalisation du Fonds sur les Pertes et Pr\u00e9judices. Ces attentes, selon lui, ont \u00e9t\u00e9 m\u00e9thodiquement d\u00e9ploy\u00e9es \u00e0 travers diverses activit\u00e9s, dont les rencontres du Vice-Pr\u00e9sident avec des leaders mondiaux et la participation des membres du Gouvernement \u00e0 des tables rondes influentes.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Quant aux acquis, le Ministre a soulign\u00e9 que la C\u00f4te d&#8217;Ivoire s&#8217;est prononc\u00e9e \u00e0 toutes les instances de prise de d\u00e9cision, illustrant ainsi une pr\u00e9sence active et influente. Il a sp\u00e9cifi\u00e9 que des partenariats et engagements financiers ont \u00e9t\u00e9 concr\u00e9tis\u00e9s. \u00ab Le pays est partie prenante de l\u2019initiative SAFE (Scaling-up Agriculture and Food Systems for Economic Development) pour un montant de 10 Milliards de dollars, la Signature d\u2019un plaidoyer pour le financement de l\u2019Education Environnementale et Climatique en Afrique de l\u2019Ouest, le Groupe CJR du Portugal a donn\u00e9 son accord pour accompagner la C\u00f4te dans sa transition \u00e9nerg\u00e9tique, l\u2019opportunit\u00e9 de soumissions de projets ivoiriens au fonds ALTERRA dot\u00e9 de 250 millions de dollars en lien avec les catastrophes que nous subissons, un cadre de partenariat sp\u00e9cifique sur la finance climat de la BOAD et l\u2019UEMOA pour accompagner notre pays dans la mobilisation de financements pour la mise en \u0153uvre de nos CDN \u00bb, a-t-il indiqu\u00e9.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Le Ministre a affirm\u00e9 que les perspectives \u00e0 venir t\u00e9moignent d&#8217;une approche proactive. Selon lui, plusieurs initiatives seront mises en \u0153uvre d\u00e8s le retour de la d\u00e9l\u00e9gation pour consolider les acquis et renforcer la position de la C\u00f4te d&#8217;Ivoire dans la lutte mondiale contre les changements climatiques.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">\u00ab Un atelier bilan afin d\u2019\u00e9laborer le rapport complet de notre participation \u00e0 cette COP28 et d\u00e9finir notre feuille de route jusqu\u2019\u00e0 la COP29 qui se tiendra du 11 au 22 novembre probablement en Moldavie. Cela reste \u00e0 \u00eatre confirm\u00e9 lors de la c\u00e9r\u00e9monie de cl\u00f4ture. Nous d\u00e9buterons notre pr\u00e9paration par la mise en place d\u2019un comit\u00e9 national d\u2019organisation des COP (changements climatiques, diversit\u00e9 biologique et d\u00e9sertification) afin d\u2019am\u00e9liorer notre organisation avec comme ma\u00eetre-mot : l\u2019anticipation ! \u00bb, a-t-il annonc\u00e9.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Exprimant sa gratitude envers le Pr\u00e9sident Alassane Ouattara et le Vice-Pr\u00e9sident KONE Tiemoko Meyliet pour leur leadership, permettant une participation pleine et enti\u00e8re de la d\u00e9l\u00e9gation ivoirienne, il a salu\u00e9 les autorit\u00e9s \u00e9miraties pour la bonne tenue de cet \u00e9v\u00e9nement majeur sur les changements climatiques. Jacques Assahor\u00e9 KONAN a conclu en remerciant tous les participants de la d\u00e9l\u00e9gation et les a exhort\u00e9s \u00e0 maintenir une synergie d&#8217;action, gage de r\u00e9ussite dans le combat contre les changements climatiques.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis le 29 novembre 2023, la C\u00f4te d&#8217;Ivoire participe activement \u00e0 la 28e Conf\u00e9rence des Parties sur le climat (COP28) \u00e0 Duba\u00ef, marquant son engagement concret dans la lutte mondiale [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4909,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","pgc_sgb_lightbox_settings":""},"categories":[58],"tags":[],"post_folder":[59],"modified_by":"MINEDD","_links":{"self":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/4906"}],"collection":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/comments?post=4906"}],"version-history":[{"count":1,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/4906\/revisions"}],"predecessor-version":[{"id":4910,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/4906\/revisions\/4910"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media\/4909"}],"wp:attachment":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media?parent=4906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/categories?post=4906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/tags?post=4906"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/post_folder?post=4906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}