{"id":4905,"date":"2023-12-06T10:17:47","date_gmt":"2023-12-06T10:17:47","guid":{"rendered":"https:\/\/did-dev.net\/mineddte\/?p=4905"},"modified":"2023-12-11T10:56:41","modified_gmt":"2023-12-11T10:56:41","slug":"cop28-la-cote-divoire-annonce-une-reduction-de-7-millions-de-tonnes-co2-equivalent-grace-au-projet-de-paiement-des-reductions-demissions-autour-du-parc-national-de-tai-pre","status":"publish","type":"post","link":"https:\/\/did-dev.net\/mineddte\/cop28-la-cote-divoire-annonce-une-reduction-de-7-millions-de-tonnes-co2-equivalent-grace-au-projet-de-paiement-des-reductions-demissions-autour-du-parc-national-de-tai-pre\/","title":{"rendered":"COP28\u00a0: LA COTE D&#8217;IVOIRE ANNONCE UNE REDUCTION DE 7 MILLIONS DE TONNES CO2 EQUIVALENT GRACE AU PROJET DE PAIEMENT DES REDUCTIONS D\u2019EMISSIONS AUTOUR DU PARC NATIONAL DE TA\u00cf (PRE)"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-4907\" src=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-1-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1003\" srcset=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-1-scaled.jpg 2560w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-1-262x103.jpg 262w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-1-847x332.jpg 847w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-1-100x39.jpg 100w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-1-1536x602.jpg 1536w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/Sans-titre-1-01-1-2048x803.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Le Ministre de l&#8217;Environnement, du D\u00e9veloppement Durable et de la Transition \u00c9cologique (MINEDDTE), Monsieur Jacques Assahor\u00e9 KONAN a officiellement annonc\u00e9 une avanc\u00e9e significative dans la lutte contre le changement climatique. C\u2019\u00e9tait le 5 d\u00e9cembre 2023, \u00e0 l\u2019occasion d\u2019un side-event tenu au pavillon de la C\u00f4te d&#8217;Ivoire \u00e0 la COP 28 de Duba\u00ef.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">\u00ab La C\u00f4te d&#8217;Ivoire a r\u00e9ussi \u00e0 r\u00e9duire ses \u00e9missions de gaz \u00e0 effet de serre de 7 millions de tonnes \u00e9quivalent carbone (tCO2eq) sur la p\u00e9riode 2020-2021, gr\u00e2ce au Projet de Paiement des R\u00e9ductions d\u2019Emissions autour du Parc National de Ta\u00ef (PRE) \u00bb, a-t-il d\u00e9clar\u00e9.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Monsieur le Ministre a rappel\u00e9, dans son intervention, le succ\u00e8s de la premi\u00e8re phase du projet d&#8217;investissement forestier de 15 millions de dollars US sur la p\u00e9riode 2018 &#8211; 2023, financ\u00e9 par le Fonds d\u2019Investissement Climatique de la Banque Mondiale (FCPF). Ce financement a permis de mettre en \u0153uvre la strat\u00e9gie nationale REDD+ dans les r\u00e9gions du Sud-ouest et du Centre du pays, contribuant ainsi \u00e0 la r\u00e9duction des \u00e9missions de gaz \u00e0 effet de serre.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Il a soulign\u00e9 l&#8217;importance du rapport sur le d\u00e9veloppement et le climat (CCDR), \u00e9labor\u00e9 avec le soutien de la Banque Mondiale et a exprim\u00e9 la volont\u00e9 du pays de contribuer \u00e0 la transition \u00e9cologique par le biais des financements carbone.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Le projet de Paiement des R\u00e9ductions d\u2019Emissions autour du Parc National de Ta\u00ef (PRE), ex\u00e9cut\u00e9 depuis 2020, a \u00e9t\u00e9 salu\u00e9 comme un mod\u00e8le pour la r\u00e9duction des \u00e9missions dans cinq r\u00e9gions du Sud-ouest de la C\u00f4te d&#8217;Ivoire. Avec un objectif de vendre un minimum de 10 millions de tCO2eq sur la p\u00e9riode 2020 &#8211; 2024, le PRE s&#8217;inscrit dans la d\u00e9marche du m\u00e9canisme REDD+, contribuant ainsi aux objectifs nationaux de r\u00e9duction des \u00e9missions.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Ce side-event a mis en lumi\u00e8re les r\u00e9sultats positifs du PRE, avec une r\u00e9duction de 7 millions de tCO2eq v\u00e9rifi\u00e9e pour la p\u00e9riode 2020 &#8211; 2021. Les paiements correspondants, estim\u00e9s \u00e0 environ 35 millions de dollars US, sont en attente de validation apr\u00e8s l&#8217;audit r\u00e9alis\u00e9 par des experts mandat\u00e9s par la Banque Mondiale.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">Monsieur Eric KONAN, le Coordonnateur du projet, a soulign\u00e9 le r\u00f4le essentiel du PRE dans la r\u00e9alisation des Contributions D\u00e9termin\u00e9es au Niveau National (CDN) de la C\u00f4te d&#8217;Ivoire. Ce projet pilote offre des perspectives d&#8217;expansion, avec une note analytique propos\u00e9e pour \u00e9valuer les opportunit\u00e9s de mise \u00e0 l&#8217;\u00e9chelle.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">La C\u00f4te d&#8217;Ivoire se positionne comme un acteur majeur dans la lutte contre le changement climatique, d\u00e9montrant que des initiatives telles que le PRE peuvent non seulement r\u00e9duire les \u00e9missions, mais aussi g\u00e9n\u00e9rer des b\u00e9n\u00e9fices \u00e9conomiques et renforcer la transition \u00e9cologique du pays. La r\u00e9duction de 7 millions de tonnes de CO2 marque une \u00e9tape importante dans la r\u00e9alisation des objectifs climatiques nationaux et t\u00e9moigne de l&#8217;engagement concret du pays en faveur d&#8217;un avenir durable.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Ministre de l&#8217;Environnement, du D\u00e9veloppement Durable et de la Transition \u00c9cologique (MINEDDTE), Monsieur Jacques Assahor\u00e9 KONAN a officiellement annonc\u00e9 une avanc\u00e9e significative dans la lutte contre le changement climatique. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4907,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","pgc_sgb_lightbox_settings":""},"categories":[58],"tags":[],"post_folder":[59],"modified_by":"MINEDD","_links":{"self":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/4905"}],"collection":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/comments?post=4905"}],"version-history":[{"count":2,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/4905\/revisions"}],"predecessor-version":[{"id":4912,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/4905\/revisions\/4912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media\/4907"}],"wp:attachment":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media?parent=4905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/categories?post=4905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/tags?post=4905"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/post_folder?post=4905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}