{"id":4895,"date":"2023-12-05T09:18:00","date_gmt":"2023-12-05T09:18:00","guid":{"rendered":"https:\/\/did-dev.net\/mineddte\/?p=4895"},"modified":"2023-12-11T11:32:04","modified_gmt":"2023-12-11T11:32:04","slug":"cop28-sur-les-changements-climatiques-le-ministre-jacques-assahore-konan-present-sur-toutes-les-arenes-de-mobilisation-des-ressources-financieres","status":"publish","type":"post","link":"https:\/\/did-dev.net\/mineddte\/cop28-sur-les-changements-climatiques-le-ministre-jacques-assahore-konan-present-sur-toutes-les-arenes-de-mobilisation-des-ressources-financieres\/","title":{"rendered":"COP28 SUR LES CHANGEMENTS CLIMATIQUES: LE MINISTRE JACQUES ASSAHORE KONAN PRESENT SUR TOUTES LES ARENES DE MOBILISATION DES RESSOURCES FINANCIERES"},"content":{"rendered":"<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\">\n<div dir=\"auto\" style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-4896\" src=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/boad-01-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1003\" srcset=\"https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/boad-01-scaled.jpg 2560w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/boad-01-262x103.jpg 262w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/boad-01-847x332.jpg 847w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/boad-01-100x39.jpg 100w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/boad-01-1536x602.jpg 1536w, https:\/\/did-dev.net\/mineddte\/wp-content\/uploads\/2023\/12\/boad-01-2048x803.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: justify;\">\n<div dir=\"auto\">\u00a0<\/div>\n<div dir=\"auto\"><span style=\"font-family: verdana, geneva, sans-serif;\">La C\u00f4te d\u2019Ivoire s\u2019est engag\u00e9e \u00e0 rehausser ses objectifs d\u2019att\u00e9nuation, de renforcer sa r\u00e9silience d\u2019adaptation et d\u2019acc\u00e9l\u00e9rer les reformes foresti\u00e8res, fonci\u00e8res, \u00e9nerg\u00e9tiques pour contribuer de mani\u00e8re efficace \u00e0 la lutte contre les changements climatiques.<\/span><\/div>\n<div dir=\"auto\">\u00a0<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: justify;\">\n<div dir=\"auto\"><span style=\"font-family: verdana, geneva, sans-serif;\">Dans le cadre de la synergie d\u2019actions entre la BOAD et l\u2019UEMOA pour la mobilisation de ressources, le Ministre de l\u2019Environnement, du D\u00e9veloppement Durable et de la Transition \u00c9cologique, Jacques Assahor\u00e9 Konan, a particip\u00e9 \u00e0 un panel sur la mobilisation de la finance climatique en Afrique de l\u2019Ouest. Cette initiative qui vise \u00e0 renforcer la coop\u00e9ration entre l\u2019\u00c9tat et les institutions financi\u00e8res r\u00e9gionales et internationales, s\u2019est tenue \u00e0 Duba\u00ef, le lundi 4 d\u00e9cembre 2023.<\/span><\/div>\n<div dir=\"auto\">\u00a0<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: justify;\">\n<div dir=\"auto\"><span style=\"font-family: verdana, geneva, sans-serif;\">R\u00e9pondant \u00e0 la question sur l&#8217;opportunit\u00e9 de ce partenariat, le Ministre Assahor\u00e9 a soulign\u00e9 l&#8217;ambitieux programme climatique de la C\u00f4te d&#8217;Ivoire. La mise en \u0153uvre de la CDN jusqu&#8217;en 2030 est estim\u00e9e \u00e0 22 milliards de dollars US, repr\u00e9sentant 17 % du PIB de 2030. Le sc\u00e9nario d\u2019att\u00e9nuation, avec trente-huit mesures, co\u00fbtera dix milliards de dollars US, cr\u00e9ant environ 34,800 emplois.<\/span><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: justify;\">\n<div dir=\"auto\">\u00a0<\/div>\n<div dir=\"auto\"><span style=\"font-family: verdana, geneva, sans-serif;\">Concernant l&#8217;adaptation qui est une priorit\u00e9 nationale, le plan vise \u00e0 r\u00e9duire la vuln\u00e9rabilit\u00e9 dans divers secteurs avec un co\u00fbt \u00e9valu\u00e9 \u00e0 douze milliards de dollars US d&#8217;ici 2030. Cette r\u00e9vision refl\u00e8te une augmentation significative par rapport aux premi\u00e8res CDN de 2012. Assahor\u00e9 a salu\u00e9 la synergie entre la BOAD et l&#8217;UEMOA, soulignant son importance strat\u00e9gique pour la C\u00f4te d&#8217;Ivoire.<\/span><\/div>\n<div dir=\"auto\">\u00a0<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: justify;\">\n<div dir=\"auto\"><span style=\"font-family: verdana, geneva, sans-serif;\">En marge de ce panel, le Ministre a marqu\u00e9 l\u2019engagement du pays en faveur de l\u2019\u00e9ducation environnementale. Il a proc\u00e9d\u00e9 \u00e0 la signature de la d\u00e9claration sur le financement de l\u2019\u00e9ducation environnementale et climatique au Greening Education Hub, une c\u00e9r\u00e9monie organis\u00e9e par l\u2019Institut des Nations Unies pour la Formation et la Recherche (UNITAR). L\u2019objectif de cette rencontre \u00e9tait de d\u00e9velopper un plaidoyer bas\u00e9 sur la mobilisation des financements en faveur de l\u2019\u00e9ducation environnementale et climatique en Afrique de l\u2019Ouest.<\/span><\/div>\n<div dir=\"auto\">\u00a0<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\" style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">La journ\u00e9e s&#8217;est conclue par une rencontre avec la Conf\u00e9d\u00e9ration G\u00e9n\u00e9rale des Entreprises de C\u00f4te d&#8217;Ivoire (CGECI), soulignant l&#8217;engagement du secteur priv\u00e9 \u00e0 accompagner la C\u00f4te d&#8217;Ivoire dans l&#8217;atteinte de ses objectifs et \u00e0 favoriser des partenariats pour mobiliser davantage de ressources.<\/span><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 La C\u00f4te d\u2019Ivoire s\u2019est engag\u00e9e \u00e0 rehausser ses objectifs d\u2019att\u00e9nuation, de renforcer sa r\u00e9silience d\u2019adaptation et d\u2019acc\u00e9l\u00e9rer les reformes foresti\u00e8res, fonci\u00e8res, \u00e9nerg\u00e9tiques pour contribuer de mani\u00e8re efficace \u00e0 la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4896,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","pgc_sgb_lightbox_settings":""},"categories":[58],"tags":[],"post_folder":[59],"modified_by":"MINEDD","_links":{"self":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/4895"}],"collection":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/comments?post=4895"}],"version-history":[{"count":1,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/4895\/revisions"}],"predecessor-version":[{"id":4897,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/4895\/revisions\/4897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media\/4896"}],"wp:attachment":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media?parent=4895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/categories?post=4895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/tags?post=4895"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/post_folder?post=4895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}