{"id":4782,"date":"2023-12-18T11:51:39","date_gmt":"2023-12-18T11:51:39","guid":{"rendered":"https:\/\/did-dev.net\/mineddte\/?p=4782"},"modified":"2023-12-22T15:32:08","modified_gmt":"2023-12-22T15:32:08","slug":"avis-a-manifestation-dinteret-recrutement-dun-consultant-national-pour-lelaboration-dun-document-de-strategie-sur-la-modelisation-de-la-decarbonisation-du-systeme","status":"publish","type":"post","link":"https:\/\/did-dev.net\/mineddte\/avis-a-manifestation-dinteret-recrutement-dun-consultant-national-pour-lelaboration-dun-document-de-strategie-sur-la-modelisation-de-la-decarbonisation-du-systeme\/","title":{"rendered":"AVIS A MANIFESTATION D\u2019INTERET: RECRUTEMENT D\u2019UN CONSULTANT NATIONAL POUR L\u2019ELABORATION D\u2019UN DOCUMENT DE STRATEGIE SUR LA MODELISATION DE LA DECARBONISATION DU SYSTEME DE GESTION DES DECHETS SOLIDES ET DES DMP, PERSPECTIVES 2050 ET LA CONCEPTION D\u2019UN GUIDE D\u2019ELABORATION DES STRATEGIES SECTORIELLES DE GESTION DES DECHETS CLIMATO- RESPONSABLES"},"content":{"rendered":"<p><span style=\"color: #ff0000;\"><strong>La date de cl\u00f4ture initiale du 01 D\u00e9cembre 2023 est prorog\u00e9e au 12 janvier 2024<\/strong><\/span><\/p>\n<p>CONTEXTE<\/p>\n<p>1. Le Gouvernement de la R\u00e9publique de C\u00f4te d\u2019Ivoire, repr\u00e9sent\u00e9 par le Minist\u00e8re de l\u2019Environnement et du D\u00e9veloppement Durable (MINEDD), a re\u00e7u un don du Fonds pour les Changements Climatiques en Afrique (FCCA) administr\u00e9 par la Banque Africaine de D\u00e9veloppement (BAD), d\u2019un montant de 277 300 USD affect\u00e9s pour la pr\u00e9paration de la C\u00f4te d\u2019Ivoire a la d\u00e9carbonisation de la gestion des D\u00e9chets solides, M\u00e9dicaux et pharmaceutiques (DMP) pour l\u2019atteinte des objectifs d\u2019att\u00e9nuation des \u00e9missions de Gaz \u00e0 Effets de Serre (GES) conform\u00e9ment aux Contributions D\u00e9termin\u00e9es au niveau National (CDN) et a l\u2019objectif 2050 de accord de Paris. L\u2019unit\u00e9 de Gestion du Projet se propose d\u2019utiliser une partie des fonds de ce don pour effectuer les paiements autoris\u00e9s au titre du contrat de recrutement au titre du contrat de recrutement d\u2019un consultant national pour l\u2019\u00e9laboration d\u2019un document de strat\u00e9gie sur la mod\u00e9lisation de la d\u00e9carbonisation du syst\u00e8me de gestion des d\u00e9chets solides et des DMP, perspectives 2050 et la conception d\u2019un guide d\u2019\u00e9laboration des strat\u00e9gies sectorielles de gestion des d\u00e9chets climato-responsables.<\/p>\n<p>2. Le pr\u00e9sent Avis \u00e0 Manifestation d\u2019int\u00e9r\u00eats a pour objectif de constituer une liste restreinte pour le recrutement d\u2019un consultant individuel national qui sera en charge de l\u2019\u00e9laboration d\u2019un document de strat\u00e9gie sur la mod\u00e9lisation de la d\u00e9carbonisation du syst\u00e8me de gestion des d\u00e9chets solides et des DMP, perspectives 2050 et la conception d\u2019un guide d\u2019\u00e9laboration des strat\u00e9gies sectorielles de gestion des d\u00e9chets climato-responsables.<\/p>\n<p>3. L\u2019objectif g\u00e9n\u00e9ral est de recruter un consultant national qui en \u00e9troite collaboration avec un consultant international, devra \u00e9laborer un document pour la mise en place d\u2019une strat\u00e9gie de long terme de gestion des d\u00e9chets solides incluant les DMP.<\/p>\n<p>4. Description de la mission du consultant<br \/>\nLes services pr\u00e9vus au titre de ce contrat comprennent les t\u00e2ches suivantes :<br \/>\na- Faire l\u2019\u00e9tude diagnostic de la gestion des d\u00e9chets solides et des DMP.<\/p>\n<p>Ce diagnostic devra comprendre :<\/p>\n<p>&#8211; Une identification des parties prenantes cl\u00e9s impliqu\u00e9es dans l\u2019\u00e9laboration et la mise en \u0153uvre de la strat\u00e9gie ;<br \/>\n&#8211; Un \u00e9tat des lieux des documents strat\u00e9giques de gestion des d\u00e9chets solides ;<br \/>\n&#8211; Une analyse sur la gestion des d\u00e9chets solides et des DMP.<\/p>\n<p>b- Elaborer un document de strat\u00e9gie de long terme de la gestion des d\u00e9chets solides int\u00e9grant les DMP.<\/p>\n<p>Ce document de strat\u00e9gie devra inclure :<\/p>\n<p>&#8211; Une mod\u00e9lisation du processus de d\u00e9carbonisation du syst\u00e8me de gestion des d\u00e9chets solides et des DMP perspective 2050 avec des sc\u00e9narii possibles afin de r\u00e9duire les GES en mettant l\u2019accent sur des innovations adoptables en C\u00f4te d\u2019Ivoire ;<br \/>\n&#8211; Un programme d\u2019actions \u00e0 court, moyen et long terme de r\u00e9duction des GES du secteur des d\u00e9chets solides et des DMP ;<br \/>\n&#8211; Un cadre de coordination et de partenariat.<\/p>\n<p>c- Concevoir un guide d\u2019\u00e9laboration des strat\u00e9gies sectorielles de gestion des d\u00e9chets climato-responsables.<\/p>\n<p>d- Faire un plaidoyer pour int\u00e9grer les innovations potentielles adoptables dans le projet Technology Needs Assessment (TNA) ;<\/p>\n<p>e- Animer un atelier de validation des livrables produits dans le cadre de l\u2019\u00e9tude.<\/p>\n<p>5. Profil du consultant<\/p>\n<p>Le consultant national devra poss\u00e9der les comp\u00e9tences et l&#8217;exp\u00e9rience requises pour ce type d\u2019investigation :<br \/>\n&#8211; Avoir un dipl\u00f4me minimum d\u2019ing\u00e9nieur ou de master (Bac + 5) en science de gestion des d\u00e9chets, \u00e9conomie circulaire, sciences de l\u2019environnement et\/ou du climat ou tout autre domaine connexe ;<br \/>\n&#8211; Avoir trois (03) ans d\u2019exp\u00e9riences dans la gestion des d\u00e9chets solides en lien avec les changements climatiques ;<br \/>\n&#8211; Avoir trois (03) ans d\u2019exp\u00e9rience dans l\u2019analyse des \u00e9missions de Gaz \u00e0 Effet de Serre (GES) et les questions de changements climatiques ;<br \/>\n&#8211; Avoir une parfaite connaissance des Contributions D\u00e9termin\u00e9es au niveau National (CDN) ;<br \/>\n&#8211; Avoir un bonne capacit\u00e9 d\u2019analyse des donn\u00e9es ;<br \/>\n&#8211; Avoir une bonne capacit\u00e9 r\u00e9dactionnelle et de communication ;<br \/>\n&#8211; Avoir une exp\u00e9rience en consultation des parties prenantes ;<br \/>\n&#8211; Ma\u00eetrise du fran\u00e7ais ;<br \/>\n&#8211; Avoir une bonne connaissance de MS Windows et MS Office et capacit\u00e9 \u00e0 utiliser les technologies informatiques et mat\u00e9riels de communication.<\/p>\n<p>6. Les crit\u00e8res d\u2019\u00e9ligibilit\u00e9, l\u2019\u00e9tablissement de la liste restreinte et la proc\u00e9dure de s\u00e9lection seront conformes aux \u00ab R\u00e8gles et Proc\u00e9dures pour l\u2019utilisation des Consultants \u00bb de la Banque Africaine de D\u00e9veloppement, \u00e9dition d\u2019Octobre 2015, qui sont disponibles sur le site web de la Banque \u00e0 l\u2019adresse : http:\/\/www.afdb.org.<\/p>\n<p>7. Crit\u00e8res d\u2019\u00e9valuation et syst\u00e8me de points utilis\u00e9s pour l\u2019\u00e9valuation des candidatures. Les candidatures re\u00e7ues seront \u00e9valu\u00e9es et classifi\u00e9es uniquement, sur la base des crit\u00e8res suivants :<\/p>\n<p>Niveau d\u2019\u00e9tudes en g\u00e9n\u00e9ral 20%<br \/>\nNiveau d\u2019\u00e9tudes par rapport au domaine de la mission 20%<br \/>\nNombre d\u2019ann\u00e9es d\u2019exp\u00e9rience en g\u00e9n\u00e9ral et pertinente par rapport \u00e0 la mission 20%<br \/>\nBonne connaissance et exp\u00e9rience du travail en C\u00f4te d\u2019Ivoire ou dans d\u2019autres pays africains dans le cadre de missions similaires 40%<br \/>\nLa note minimale requise pour \u00eatre \u00e9ligible est de 70 points sur 100.<br \/>\n8. Qualifications et Exp\u00e9riences minimales requises<br \/>\nLe Consultant candidat doit :<\/p>\n<p>&#8211; Etre titulaire d\u2019un dipl\u00f4me d\u2019ing\u00e9nieur ou de master (Bac + 5) en science de gestion des d\u00e9chets, \u00e9conomie circulaire, sciences de l\u2019environnement et\/ou du climat ou tout autre domaine connexe ;<br \/>\n&#8211; Justifier d\u2019au moins une exp\u00e9rience de trois (03) ans pertinentes dans l&#8217;\u00e9laboration de strat\u00e9gies\/politiques li\u00e9es \u00e0 l&#8217;environnement ou \u00e0 la gestion des d\u00e9chets est requis<br \/>\n&#8211; Justifier d\u2019au moins une exp\u00e9rience de trois (03) ans dans la gestion des d\u00e9chets solides en lien avec les changements climatiques ;<br \/>\n&#8211; Justifier d\u2019au moins une exp\u00e9rience de trois (03) ans dans l\u2019analyse des \u00e9missions de GES et les questions de changements climatiques ;<br \/>\n&#8211; Avoir une parfaite connaissance des Contributions D\u00e9termin\u00e9es au niveau National (CDN) :<br \/>\n&#8211; Faire preuve d\u2019une ma\u00eetrise parfaite de la langue fran\u00e7aise.<\/p>\n<p>9. La p\u00e9riode pr\u00e9vue pour l\u2019ex\u00e9cution de la mission est de quarante-cinq (45) jours ouvrables cumulables y compris la p\u00e9riode de r\u00e9daction et de validation du document de strat\u00e9gie de long terme de la gestion des d\u00e9chets solides en int\u00e9grant les DMP et du guide d\u2019\u00e9laboration des strat\u00e9gies sectorielles de gestion des d\u00e9chets climato-responsables \u00e0 compter de la date de signature du contrat.<\/p>\n<p>La p\u00e9riode envisag\u00e9e pour la prestation des services couvrira la p\u00e9riode de novembre 2023 \u00e0 F\u00e9vrier 2024.<br \/>\nLieu d\u2019affectation : Abidjan (C\u00f4te d\u2019Ivoire) au sein du Programme National Changement Climatique.<\/p>\n<p>10. Le Minist\u00e8re de l\u2019Environnement et du D\u00e9veloppement Durable (MINEDD) \u00e0 travers le Programme National Changement climatique (PNCC) invite les consultants ind\u00e9pendants \u00e0 pr\u00e9senter leur candidature en vue de fournir les services d\u00e9crits ci-dessus. Les consultants int\u00e9ress\u00e9s doivent produire les informations sur leur capacit\u00e9 et exp\u00e9rience d\u00e9montrant qu\u2019ils sont qualifi\u00e9s pour le suivi-\u00e9valuation de projet en lien avec les changements climatiques.<\/p>\n<p>11. Les candidats sont invit\u00e9s \u00e0 joindre dans le dossier manifestation d&#8217;int\u00e9r\u00eat les documents suivants :<\/p>\n<p>&#8211; Un curriculum Vitae (CV) ;<br \/>\n&#8211; Une lettre de motivation ;<br \/>\n&#8211; Les dipl\u00f4mes, attestations et certificats de formation sur leurs comp\u00e9tences dans le domaine de la mission.<\/p>\n<p>12. Les candidats int\u00e9ress\u00e9s peuvent obtenir des informations suppl\u00e9mentaires \u00e0 l&#8217;adresse mentionn\u00e9e ci-dessous aux heures d\u2019ouverture de bureaux suivantes : du : du lundi au vendredi de 07 heures 30 minutes \u00e0 12 heures 30 minutes et de 13 heures 30 minutes \u00e0 16 heures 30 minutes (jours ouvrables et heure locale) ; ou en faisant une demande par e-mail \u00e0 l\u2019adresse leaticiaamon12@gmail.com ou projetdmp2023@gmail.com.<\/p>\n<p>13. Les expressions d&#8217;int\u00e9r\u00eat en fran\u00e7ais doivent \u00eatre d\u00e9pos\u00e9es en trois (03) exemplaires dont un (01) original \u00e0 l&#8217;adresse mentionn\u00e9e ci-dessous et par courriel au plus tard le Vendredi 01 D\u00e9cembre 2023 \u00e0 16 heures 00 minute (heure locale). L\u2019ouverture publique des plis ayant lieu le m\u00eame jour \u00e0 16 heures 30 minutes GMT ; et porter express\u00e9ment la mention \u00ab Avis \u00e0 Manifestation d\u2019int\u00e9r\u00eat pour la s\u00e9lection d\u2019un Consultant national pour l\u2019\u00e9laboration d\u2019un document de strat\u00e9gie sur la mod\u00e9lisation de la d\u00e9carbonisation du syst\u00e8me de gestion des d\u00e9chets solides et des DMP, perspectives 2050 et la conception d\u2019un guide d\u2019\u00e9laboration des strat\u00e9gies sectorielles de gestion des d\u00e9chets climato- responsables du Projet la pr\u00e9paration de la C\u00f4te d\u2019Ivoire a la d\u00e9carbonisation de la gestion des D\u00e9chets solides, M\u00e9dicaux et pharmaceutiques (DMP) pour l\u2019atteinte des objectifs d\u2019att\u00e9nuation des conform\u00e9ment aux CDN et a l\u2019objectif 2050 de l\u2019accord de Paris \u00bb \u00e0 n\u2019ouvrir qu\u2019en s\u00e9ance d\u2019ouverture des plis.<\/p>\n<p>Unit\u00e9 de Gestion du Programme National Changement Climatique (UG-PNCC)<br \/>\n\u00c0 l&#8217;attention de Monsieur le Coordonnateur du projet DMP<br \/>\nSise \u00e0 Abidjan, Riviera Palmeraie, cit\u00e9 du bonheur non loin de la SODECI<br \/>\nTel : +225 07 59 50 11 19 \/ +225 05 66 90 27 96<br \/>\nE-mail : leaticiaamon12@gmail.com ou projetdmp2023@gmail.com.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La date de cl\u00f4ture initiale du 01 D\u00e9cembre 2023 est prorog\u00e9e au 12 janvier 2024 CONTEXTE 1. Le Gouvernement de la R\u00e9publique de C\u00f4te d\u2019Ivoire, repr\u00e9sent\u00e9 par le Minist\u00e8re de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4935,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","pgc_sgb_lightbox_settings":""},"categories":[58],"tags":[],"post_folder":[59],"modified_by":"MINEDD","_links":{"self":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/4782"}],"collection":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/comments?post=4782"}],"version-history":[{"count":3,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/4782\/revisions"}],"predecessor-version":[{"id":4936,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/posts\/4782\/revisions\/4936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media\/4935"}],"wp:attachment":[{"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/media?parent=4782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/categories?post=4782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/tags?post=4782"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/did-dev.net\/mineddte\/wp-json\/wp\/v2\/post_folder?post=4782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}